{"id":12472,"date":"2017-06-26T15:40:32","date_gmt":"2017-06-26T13:40:32","guid":{"rendered":"http:\/\/www.aprophysio.de\/?p=12472"},"modified":"2017-06-26T15:40:32","modified_gmt":"2017-06-26T13:40:32","slug":"knieschmerzen","status":"publish","type":"post","link":"https:\/\/aprophysio.de\/index.php\/2017\/06\/26\/knieschmerzen\/","title":{"rendered":"Knieschmerzen"},"content":{"rendered":"<p>[fusion_builder_container hundred_percent=&#8220;no&#8220; equal_height_columns=&#8220;no&#8220; menu_anchor=&#8220;&#8220; hide_on_mobile=&#8220;small-visibility,medium-visibility,large-visibility&#8220; class=&#8220;&#8220; id=&#8220;&#8220; background_color=&#8220;&#8220; background_image=&#8220;&#8220; background_position=&#8220;center center&#8220; background_repeat=&#8220;no-repeat&#8220; fade=&#8220;no&#8220; background_parallax=&#8220;none&#8220; enable_mobile=&#8220;no&#8220; parallax_speed=&#8220;0.3&#8243; video_mp4=&#8220;&#8220; video_webm=&#8220;&#8220; video_ogv=&#8220;&#8220; video_url=&#8220;&#8220; video_aspect_ratio=&#8220;16:9&#8243; video_loop=&#8220;yes&#8220; video_mute=&#8220;yes&#8220; video_preview_image=&#8220;&#8220; border_size=&#8220;&#8220; border_color=&#8220;&#8220; border_style=&#8220;solid&#8220; margin_top=&#8220;&#8220; margin_bottom=&#8220;&#8220; padding_top=&#8220;&#8220; padding_right=&#8220;&#8220; padding_bottom=&#8220;&#8220; padding_left=&#8220;&#8220;][fusion_builder_row][fusion_builder_column type=&#8220;1_1&#8243; layout=&#8220;1_1&#8243; spacing=&#8220;&#8220; center_content=&#8220;no&#8220; hover_type=&#8220;none&#8220; link=&#8220;&#8220; min_height=&#8220;&#8220; hide_on_mobile=&#8220;small-visibility,medium-visibility,large-visibility&#8220; class=&#8220;&#8220; id=&#8220;&#8220; background_color=&#8220;&#8220; background_image=&#8220;&#8220; background_position=&#8220;left top&#8220; background_repeat=&#8220;no-repeat&#8220; border_size=&#8220;0&#8243; border_color=&#8220;&#8220; border_style=&#8220;solid&#8220; border_position=&#8220;all&#8220; padding=&#8220;&#8220; dimension_margin=&#8220;&#8220; animation_type=&#8220;&#8220; animation_direction=&#8220;left&#8220; animation_speed=&#8220;0.3&#8243; animation_offset=&#8220;&#8220; last=&#8220;no&#8220;][fusion_text]<\/p>\n<p>Heute widmen wir uns einer weiteren gro\u00dfen Problemzone, den Knieschmerzen. Jeder hatte sie schon einmal. Manchmal kommen sie nur kurz, manchmal halten sie l\u00e4nger an und manchmal gehen sie nicht mehr weg. In diesem Artikel wollen wir auf Ursachen, Unterschiede der Knieschmerzen und auf einige \u00dcbungen eingehen.<\/p>\n<h2>Ursachen von Knieschmerzen<\/h2>\n<p>Die Ursachen k\u00f6nnen ganz vielf\u00e4ltig sein:<\/p>\n<ul>\n<li>akutes Thema (Sturz, Verdrehung)<\/li>\n<li>Postoperativer Schmerz<\/li>\n<li>Allgemein Arthrose\/Verschlei\u00df<\/li>\n<li>\u00dcberlastung und Fehlbelastung durch z.B. Schonung des anderen Beins<\/li>\n<li>Gelenkentz\u00fcndung<\/li>\n<li>Hypertonus der umliegenden Muskulatur z.B. des Oberschenkelmuskels<\/li>\n<li>Alte\/verschleppte Verletzung des Bandapparates und der Menisken<\/li>\n<li>H\u00fcftprobleme wie Arthrose und Dysplasie<\/li>\n<li>Anatomische Fehlstellungen im gesamten K\u00f6rper (Kompensation)<\/li>\n<\/ul>\n<p>Wir unterscheiden bei den Arten der Knieschmerzen 4 Positionen:<\/p>\n<ol>\n<li>Schmerzen vorne hinter der Kniescheibe (retropatellar)<\/li>\n<li>Schmerzen hinten (Kapselschwellung, Baker-Z\u00fcste oder Meniskus)<\/li>\n<li>Schmerzen lateral (Oberschenkelau\u00dfenseite, Au\u00dfenb\u00e4nder)<\/li>\n<li>Schmerzen medial (Oberschenkelinnenseite, B\u00e4nder, Meniskus)<\/li>\n<\/ol>\n<h2>Was ist am wichtigsten f\u00fcr ein gesundes und schmerzfreies Knie?<\/h2>\n<p>Das l\u00e4sst sich ganz einfach mit einer Wort beantworten: DIE BEINACHSE. Die physiologische Beinachse ausgehend von der vorderen oberen Beckenspitze vers\u00e4uft eine gerade Linie durch die Mitte der Kniescheibe (Patella) und weiter zur zweiten Zehe. Dabei gibt es 3 Pathologische Abweichungen:<\/p>\n<ol>\n<li>\u201eX-Beine\u201c &#8211; Knie weicht nach innen von der Beinachse ab<\/li>\n<li>\u201eO-Beine\u201c &#8211; Knie weichen nach au\u00dfen von der Beinachse ab<\/li>\n<li>\u201eInnen-\/Au\u00dfenrotation des Unterschenkels und Fu\u00dfes\u201c \u2013 2. Zehe weicht von innen\/au\u00dfen von der Beinachse ab<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<h2>Folgende 6 \u00dcbungen helfen bei der Stabilisation des Knies<\/h2>\n<div style=\"width: 320px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-12472-1\" width=\"320\" height=\"576\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"http:\/\/www.aprophysio.de\/cms\/wp-content\/uploads\/2017\/06\/Knie-Eric.mp4?_=1\" \/><a href=\"http:\/\/www.aprophysio.de\/cms\/wp-content\/uploads\/2017\/06\/Knie-Eric.mp4\">http:\/\/www.aprophysio.de\/cms\/wp-content\/uploads\/2017\/06\/Knie-Eric.mp4<\/a><\/video><\/div>\n<p>[\/fusion_text][fusion_separator style_type=&#8220;none&#8220; hide_on_mobile=&#8220;small-visibility,medium-visibility,large-visibility&#8220; class=&#8220;&#8220; id=&#8220;&#8220; sep_color=&#8220;&#8220; top_margin=&#8220;15&#8243; bottom_margin=&#8220;&#8220; border_size=&#8220;&#8220; icon=&#8220;&#8220; icon_circle=&#8220;&#8220; icon_circle_color=&#8220;&#8220; width=&#8220;&#8220; alignment=&#8220;center&#8220; \/][fusion_text]<\/p>\n<h2>Behandlungsm\u00f6glichkeiten<\/h2>\n<p>Bei der Behandlung haben wir drei M\u00f6glichkeiten. Zun\u00e4chst einmal m\u00fcssen Positionen\/Haltungen\/Bewegungen vermieden werden, die zu den Beschwerden f\u00fchren. Das klingt zwar ganz banal, jedoch entwickeln wir im Laufe der Zeit bestimmte Bewegungs- und Haltungsmuster, die ganz einfach schlecht f\u00fcr unsere Gelenke sind. Oft erfolgt das unbewusst. Diese wieder rauszubekommen geht nur durch bewusste \u00dcbungen.<\/p>\n<p>Als zweites muss die Beinachse durch spezifisches Training stabilisiert werden. Das Geht durch unterschiedliche Variationen von Kniebeugen, Lunges, Einbeinstand, Balancier\u00fcbungen, Ausdauer\u00fcbungen und spezifische Bein\u00fcbungen in liegen.<\/p>\n<p>Als drittes hilft die Stabilisierung der Knie durch Bandagen oder Tapes. <a href=\"http:\/\/www.aprophysio.de\/hilfsgeraete-orthesen-bandagen\/\">Hier findest Du einen Artikel dazu.<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Wir hoffen durch diesen Artikel einen kleinen und kurzen \u00dcberblick \u00fcber Knieprobleme gegeben zu haben. Bei Fragen stehen wir Dir gerne unter der 030 20629631 zur Verf\u00fcgung.<\/p>\n<p>&nbsp;<\/p>\n<p>Deine Gesundheit nehmen wir pers\u00f6nlich!<\/p>\n<p>Dein AproPhysio-Team<\/p>\n<p>[\/fusion_text][\/fusion_builder_column][\/fusion_builder_row][\/fusion_builder_container]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[fusion_builder_container hundred_percent=&#8220;no&#8220; equal_height_columns=&#8220;no&#8220; menu_anchor=&#8220;&#8220; hide_on_mobile=&#8220;small-visibility,medium-visibility,large-visibility&#8220; class=&#8220;&#8220; id=&#8220;&#8220; background_color=&#8220;&#8220; background_image=&#8220;&#8220; background_position=&#8220;center center&#8220; background_repeat=&#8220;no-repeat&#8220; fade=&#8220;no&#8220; background_parallax=&#8220;none&#8220; enable_mobile=&#8220;no&#8220; parallax_speed=&#8220;0.3&#8243; video_mp4=&#8220;&#8220; video_webm=&#8220;&#8220; video_ogv=&#8220;&#8220; video_url=&#8220;&#8220; video_aspect_ratio=&#8220;16:9&#8243; video_loop=&#8220;yes&#8220; video_mute=&#8220;yes&#8220; video_preview_image=&#8220;&#8220; border_size=&#8220;&#8220; border_color=&#8220;&#8220; [&#8230;] <\/p>\n","protected":false},"author":1,"featured_media":12359,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,50],"tags":[],"class_list":["post-12472","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-therapie"],"featured_image_src":null,"featured_image_src_square":null,"author_info":{"display_name":"admin","author_link":"https:\/\/aprophysio.de\/index.php\/author\/afleischmann_oi8xdaka\/"},"_links":{"self":[{"href":"https:\/\/aprophysio.de\/index.php\/wp-json\/wp\/v2\/posts\/12472","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aprophysio.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aprophysio.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aprophysio.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aprophysio.de\/index.php\/wp-json\/wp\/v2\/comments?post=12472"}],"version-history":[{"count":0,"href":"https:\/\/aprophysio.de\/index.php\/wp-json\/wp\/v2\/posts\/12472\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aprophysio.de\/index.php\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/aprophysio.de\/index.php\/wp-json\/wp\/v2\/media?parent=12472"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aprophysio.de\/index.php\/wp-json\/wp\/v2\/categories?post=12472"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aprophysio.de\/index.php\/wp-json\/wp\/v2\/tags?post=12472"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}